{"id":24886,"date":"2024-09-18T16:00:00","date_gmt":"2024-09-18T16:00:00","guid":{"rendered":"https:\/\/workbao.net\/archives\/24886"},"modified":"2024-09-18T16:00:00","modified_gmt":"2024-09-18T16:00:00","slug":"%e7%a7%8b%e7%94%b0%e5%8e%bf%e8%83%bd%e4%bb%a3%e5%b8%82%e7%9a%84%e6%8b%8d%e5%8d%96%ef%bc%9a2-3-%e4%b8%87%e6%97%a5%e5%85%83-%e5%86%9c%e7%94%b0-1137-%e5%b9%b3%e6%96%b9%e7%b1%b3","status":"publish","type":"post","link":"https:\/\/workbao.net\/en\/\u79cb\u7530\u53bf\u80fd\u4ee3\u5e02\u7684\u62cd\u5356\uff1a2-3-\u4e07\u65e5\u5143-\u519c\u7530-1137-\u5e73\u65b9\u7c73\/","title":{"rendered":"\u79cb\u7530\u53bf\u80fd\u4ee3\u5e02\u7684\u62cd\u5356\uff1a2.3 \u4e07\u65e5\u5143 \u519c\u7530 1137 \u5e73\u65b9\u7c73"},"content":{"rendered":"<div class=\"container1\">\n<a class=\"prev\" onclick=\"plusSlides(-1)\">&#10094;<\/a><a class=\"next\" onclick=\"plusSlides(1)\">&#10095;<\/a><\/p>\n<div class=\"thumbnails\"><\/div>\n<\/div>\n<p>;<a href=\"https:\/\/maps.apple.com\/?ll=\u51c6\u786e\u4f4d\u7f6e\" target=\"_blank\" rel=\"noopener\">Open Apple Maps to view the exact location of the project&gt;&gt;<\/a>;<\/p>\n<h2>Special Sales<label for=\"bidformat-modal\" class=\"vlink\" title=\"The difference between period bidding and special sales\"><sup><i class=\"icon-help\"><\/i><\/sup><\/label><span class=\"normal\"> (<label for=\"pasts-modal\" class=\"vlink\" title=\"View the sales history of this property\">\u7b2c 10 \u6b21\u9500\u552e<\/label>) <\/span><\/h2>\n<dl class=\"props\">\n<dt class=\"dtqq\">\n  Jurisdictional Court\n <\/dt>\n<dd class=\"ddqq\">\n  Akita District Court Main Office\n <\/dd>\n<dt class=\"dtqq\">\n  Case Number\n <\/dt>\n<dd class=\"ddqq\">\n  \u4ee4\u548c 04 \u5e74(\u30b1)\u7b2c 36 \u53f7\n <\/dd>\n<dt class=\"dtqq\">\n  Sales base price\n <\/dt>\n<dd class=\"ddqq\">\n  23,000 \u65e5\u5143\n <\/dd>\n<dt class=\"dtqq\">\n  Purchase application margin amount\n <\/dt>\n<dd class=\"ddqq\">\n  4,600 \u65e5\u5143\n <\/dd>\n<dt class=\"dtqq\">\n  Available price\n <\/dt>\n<dd class=\"ddqq\">\n  18,400 yen\n <\/dd>\n<\/dl>\n<h2>Property Overview<\/h2>\n<dl class=\"props\">\n<dt class=\"dtqq\">\n  location\n <\/dt>\n<dd class=\"ddqq\">\n  \u79cb\u7530\u53bf\u4ec1\u8d3a\u4fdd\u5e02\u8c61\u6cfb\u753a\u6a2a\u5188\u5b57\u4e0b\u957f\u7530 145 \u756a\n <\/dd>\n<dt class=\"dtqq\">\n  Evaluate traffic\n <\/dt>\n<dd class=\"ddqq\">\n  JR \u7fbd\u8d8a\u672c\u7ebf\u300c\u8c61\u6cfb\u300d\u7ad9\u4e1c\u5357\u7ea6 7.5km\uff08\u9053\u8def\u8ddd\u79bb\uff09\n <\/dd>\n<dt class=\"dtqq\">\n  Land Area\n <\/dt>\n<dd class=\"ddqq\">\n  1,137m  <sup>2<\/sup> (343.9 pings)\n <\/dd>\n<dt class=\"dtqq\">\n  Land\n <\/dt>\n<dd class=\"ddqq\">\n  field\n <\/dd>\n<dt class=\"dtqq\">\n  Area of use\n <\/dt>\n<dd class=\"ddqq\">\n  No designation outside the urban planning area\n <\/dd>\n<dt class=\"dtqq\">\n  Property Number\n <\/dt>\n<dd class=\"ddqq\">\n<ul class=\"prop-kinds\">\n<li>1. Land (agricultural land)<\/li>\n<\/ul>\n<\/dd>\n<\/dl>\n<h2>Property Details<\/h2>\n<dl class=\"props\">\n<dt class=\"dtqq\">\n  Property Number\n <\/dt>\n<dd class=\"ddqq\">\n  1\n <\/dd>\n<dt class=\"dtqq\">\n  category\n <\/dt>\n<dd class=\"ddqq\">\n  Land (agricultural land)\n <\/dd>\n<dt class=\"dtqq\">\n  location\n <\/dt>\n<dd class=\"ddqq\">\n  \u4ec1\u8d3a\u4fdd\u5e02\u8c61\u6cfb\u753a\u6a2a\u5188\u5b57\u4e0b\u957f\u7530 145 \u756a\n <\/dd>\n<dt class=\"dtqq\">\n  Land registration\n <\/dt>\n<dd class=\"ddqq\">\n  field\n <\/dd>\n<dt class=\"dtqq\">\n  Land area (registered)\n <\/dt>\n<dd class=\"ddqq\">\n  1,137m  <sup>2<\/sup> (343.9 pings)\n <\/dd>\n<dt class=\"dtqq\">\n  Area of use\n <\/dt>\n<dd class=\"ddqq\">\n  No designation outside the urban planning area\n <\/dd>\n<\/dl>\n<dl class=\"props full\">\n<dt class=\"dtqq\">\n  Bidding Qualifications\n <\/dt>\n<dd class=\"ddqq\">\n  \u53ea\u6709\u62e5\u6709\u90fd\u9053\u5e9c\u53bf\u77e5\u4e8b\u6216\u519c\u4e1a\u59d4\u5458\u4f1a\u7b49\u9881\u53d1\u7684\u8d2d\u4e70\u8d44\u683c\u8bc1\u660e\u7684\u4eba\u624d\u80fd\u5bf9\u519c\u5730\u548c\u7267\u8349\u653e\u7267\u5730\u63d0\u51fa\u8d2d\u4e70\u7533\u8bf7\u3002\u6b64\u5916\uff0c\u5f53\u8fd9\u4e9b\u4eba\u6210\u4e3a\u6700\u9ad8\u51fa\u4ef7\u8d2d\u4e70\u4eba\u7b49\u65f6\uff0c\u5fc5\u987b\u5728\u9500\u552e\u51b3\u5b9a\u65e5\u671f\u4e4b\u524d\u5411\u6267\u884c\u6cd5\u9662\u63d0\u4ea4\u90fd\u9053\u5e9c\u53bf\u77e5\u4e8b\u7b49\u9881\u53d1\u7684\u8bc1\u660e\u8bb8\u53ef\u7684\u6587\u4ef6\u6216\u63d0\u4ea4\u53d7\u7406\u8bc1\u660e\u3002\u5173\u4e8e\u8d2d\u4e70\u8d44\u683c\u8bc1\u660e\u7684\u83b7\u53d6\u7b49\uff0c\u8bf7\u5411\u8be5\u519c\u5730\u7b49\u6240\u5728\u7684\u90fd\u9053\u5e9c\u53bf\u529e\u516c\u5ba4\u6216\u519c\u4e1a\u59d4\u5458\u4f1a\u7b49\u54a8\u8be2\u3002\n <\/dd>\n<dt class=\"dtqq\">\n  Precautions\n <\/dt>\n<dd class=\"ddqq\">\n  \u8bf7\u52a1\u5fc5\u4e0b\u8f7d\u5e76\u786e\u8ba4\u7269\u4e1a\u8d44\u6599 3 \u4ef6\u5957\uff08\u7269\u4e1a\u8be6\u7ec6\u8bf4\u660e\u4e66\u3001\u73b0\u72b6\u8c03\u67e5\u62a5\u544a\u548c\u8bc4\u4f30\u4e66\u7b49\uff09\uff08\u53ef\u80fd\u5b58\u5728\u6c11\u4e8b\u6267\u884c\u6cd5\u7b2c 63 \u6761\u7b2c 2 \u9879\u7b2c 1 \u53f7\u7684\u7533\u8bf7\u7b49\u60c5\u51b5\uff09\u3002\u4ece\u672c\u7cfb\u7edf\u4e0b\u8f7d\u7684\u201c\u73b0\u72b6\u8c03\u67e5\u62a5\u544a\u201d\u548c\u201c\u8bc4\u4f30\u4e66\u201d\u4e2d\u5f15\u7528\u7684\u7167\u7247\u3001\u8d44\u6599\u548c\u56fe\u7eb8\u5728\u672c\u7cfb\u7edf\u4e0a\u53ef\u80fd\u672a\u9644\u52a0\u3002\n <\/dd>\n<\/dl>\n<h2>Sales Schedule<\/h2>\n<dl class=\"props\">\n<dt class=\"dtqq\">\n  Special sale browsing start date\n <\/dt>\n<dd class=\"ddqq\">\n  September 19, 2024 (Thursday)\n <\/dd>\n<dt class=\"dtqq\">\n  Special sales period\n <\/dt>\n<dd class=\"ddqq\">\n  Thursday, September 19, 2024 only\n <\/dd>\n<dt class=\"dtqq\">\n  state\n <\/dt>\n<dd class=\"ddqq\">\n  Finish\n <\/dd>\n<dt class=\"dtqq\">\n  schedule\n <\/dt>\n<dd class=\"ddqq\">\n  Annual sales schedule\/ Akita District Court Main Office\n <\/dd>\n<\/dl>\n<h2>Past Sales<\/h2>\n<dl class=\"props\">\n<dt class=\"dtqq\">\n  1st time\n <\/dt>\n<dd class=\"ddqq\">\n  26 \u4e07\u65e5\u5143 (2023.05.17 \u672a\u552e\u51fa)\n <\/dd>\n<dt class=\"dtqq\">\n  2nd time\n <\/dt>\n<dd class=\"ddqq\">\n  26 \u4e07\u65e5\u5143 (2023.05.19 \u672a\u552e\u51fa)\n <\/dd>\n<dt class=\"dtqq\">\n  3rd time\n <\/dt>\n<dd class=\"ddqq\">\n  15 \u4e07\u65e5\u5143 (2023.09.13 \u672a\u552e\u51fa)\n <\/dd>\n<dt class=\"dtqq\">\n  4th\n <\/dt>\n<dd class=\"ddqq\">\n  15 \u4e07\u65e5\u5143 (2023.09.15 \u672a\u552e\u51fa)\n <\/dd>\n<dt class=\"dtqq\">\n  No. 5\n <\/dt>\n<dd class=\"ddqq\">\n  9 \u4e07\u65e5\u5143 (2024.01.17 \u672a\u552e\u51fa)\n <\/dd>\n<dt class=\"dtqq\">\n  6th\n <\/dt>\n<dd class=\"ddqq\">\n  9 \u4e07\u65e5\u5143 (2024.01.19 \u672a\u552e\u51fa)\n <\/dd>\n<dt class=\"dtqq\">\n  No. 7\n <\/dt>\n<dd class=\"ddqq\">\n  4 \u4e07\u65e5\u5143 (2024.04.17 \u672a\u552e\u51fa)\n <\/dd>\n<dt class=\"dtqq\">\n  No. 8\n <\/dt>\n<dd class=\"ddqq\">\n  4 \u4e07\u65e5\u5143 (2024.04.19 \u672a\u552e\u51fa)\n <\/dd>\n<dt class=\"dtqq\">\n  9th\n <\/dt>\n<dd class=\"ddqq\">\n  2 \u4e07\u65e5\u5143 (2024.09.18 \u672a\u552e\u51fa)\n <\/dd>\n<\/dl>\n<p><i class=\"icon-link-ext\"><\/i><\/p>","protected":false},"excerpt":{"rendered":"<p>\u7279\u522b\u9500\u552e\u671f\u95f4\u4ec5\u4e3a 2024 \u5e74 9 \u6708 19 \u65e5\uff1b\u516c\u544a\u65e5\u671f\uff1a2024 \u5e74 9 \u6708 19 \u65e5\uff1b\u7ba1\u8f96\u6cd5\u9662\uff1a\u79cb\u7530\u5730\u65b9\u88c1\u5224\u6240\u672c\u5e81\uff1b\u6848\u4ef6\u7f16\u53f7\uff1a\u4ee4\u548c04\u5e74(\u30b1)\u7b2c36\u53f7\uff1b\u8f66\u7ad9\u8ddd\u79bb\uff1a\u4e0a\u6d5c\u7ad9 77 \u5206\uff08\u7ea6 6.1 \u516c\u91cc\uff09\uff1b\u7ade\u4e70\u4fdd\u8bc1\u91d1\uff1a46 \u4e07\u65e5\u5143\u2026\u2026<\/p>","protected":false},"author":310,"featured_media":24887,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[574],"tags":[1361,340,1139,173,1360],"class_list":["post-24886","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-574","tag-1361","tag-340","tag-1139","tag-173","tag-1360"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.0 (Yoast SEO v24.0) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u79cb\u7530\u53bf\u80fd\u4ee3\u5e02\u7684\u62cd\u5356\uff1a2.3 \u4e07\u65e5\u5143 \u519c\u7530 1137 \u5e73\u65b9\u7c73 - Japanese real estate auctioned by the court<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/workbao.net\/en\/\u79cb\u7530\u53bf\u80fd\u4ee3\u5e02\u7684\u62cd\u5356\uff1a2-3-\u4e07\u65e5\u5143-\u519c\u7530-1137-\u5e73\u65b9\u7c73\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u79cb\u7530\u53bf\u80fd\u4ee3\u5e02\u7684\u62cd\u5356\uff1a2.3 \u4e07\u65e5\u5143 \u519c\u7530 1137 \u5e73\u65b9\u7c73\" \/>\n<meta property=\"og:description\" content=\"\u7279\u522b\u9500\u552e\u671f\u95f4\u4ec5\u4e3a 2024 \u5e74 9 \u6708 19 \u65e5\uff1b\u516c\u544a\u65e5\u671f\uff1a2024 \u5e74 9 \u6708 19 \u65e5\uff1b\u7ba1\u8f96\u6cd5\u9662\uff1a\u79cb\u7530\u5730\u65b9\u88c1\u5224\u6240\u672c\u5e81\uff1b\u6848\u4ef6\u7f16\u53f7\uff1a\u4ee4\u548c04\u5e74(\u30b1)\u7b2c36\u53f7\uff1b\u8f66\u7ad9\u8ddd\u79bb\uff1a\u4e0a\u6d5c\u7ad9 77 \u5206\uff08\u7ea6 6.1 \u516c\u91cc\uff09\uff1b\u7ade\u4e70\u4fdd\u8bc1\u91d1\uff1a46 \u4e07\u65e5\u5143\u2026\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/workbao.net\/en\/\u79cb\u7530\u53bf\u80fd\u4ee3\u5e02\u7684\u62cd\u5356\uff1a2-3-\u4e07\u65e5\u5143-\u519c\u7530-1137-\u5e73\u65b9\u7c73\/\" \/>\n<meta property=\"og:site_name\" content=\"Japanese real estate auctioned by the court\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=61567565904984\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-18T16:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/workbao.net\/wp-content\/uploads\/2024\/09\/824166a04dec1506552b6f4e43e6f443.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"60\" \/>\n\t<meta property=\"og:image:height\" content=\"45\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"\u79cb\u7530\u5730\u65b9\u88c1\u5224\u6240\u672c\u5e81\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u79cb\u7530\u5730\u65b9\u88c1\u5224\u6240\u672c\u5e81\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/workbao.net\/%e7%a7%8b%e7%94%b0%e5%8e%bf%e8%83%bd%e4%bb%a3%e5%b8%82%e7%9a%84%e6%8b%8d%e5%8d%96%ef%bc%9a2-3-%e4%b8%87%e6%97%a5%e5%85%83-%e5%86%9c%e7%94%b0-1137-%e5%b9%b3%e6%96%b9%e7%b1%b3\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/workbao.net\/%e7%a7%8b%e7%94%b0%e5%8e%bf%e8%83%bd%e4%bb%a3%e5%b8%82%e7%9a%84%e6%8b%8d%e5%8d%96%ef%bc%9a2-3-%e4%b8%87%e6%97%a5%e5%85%83-%e5%86%9c%e7%94%b0-1137-%e5%b9%b3%e6%96%b9%e7%b1%b3\/\"},\"author\":{\"name\":\"\u79cb\u7530\u5730\u65b9\u88c1\u5224\u6240\u672c\u5e81\",\"@id\":\"https:\/\/workbao.net\/#\/schema\/person\/12758d64054b3f26a9e105241c0164dd\"},\"headline\":\"\u79cb\u7530\u53bf\u80fd\u4ee3\u5e02\u7684\u62cd\u5356\uff1a2.3 \u4e07\u65e5\u5143 \u519c\u7530 1137 \u5e73\u65b9\u7c73\",\"datePublished\":\"2024-09-18T16:00:00+00:00\",\"dateModified\":\"2024-09-18T16:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/workbao.net\/%e7%a7%8b%e7%94%b0%e5%8e%bf%e8%83%bd%e4%bb%a3%e5%b8%82%e7%9a%84%e6%8b%8d%e5%8d%96%ef%bc%9a2-3-%e4%b8%87%e6%97%a5%e5%85%83-%e5%86%9c%e7%94%b0-1137-%e5%b9%b3%e6%96%b9%e7%b1%b3\/\"},\"wordCount\":6,\"publisher\":{\"@id\":\"https:\/\/workbao.net\/#organization\"},\"image\":{\"@id\":\"https:\/\/workbao.net\/%e7%a7%8b%e7%94%b0%e5%8e%bf%e8%83%bd%e4%bb%a3%e5%b8%82%e7%9a%84%e6%8b%8d%e5%8d%96%ef%bc%9a2-3-%e4%b8%87%e6%97%a5%e5%85%83-%e5%86%9c%e7%94%b0-1137-%e5%b9%b3%e6%96%b9%e7%b1%b3\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/workbao.net\/wp-content\/uploads\/2024\/09\/824166a04dec1506552b6f4e43e6f443.jpg\",\"keywords\":[\"\u4ec1\u8d3a\u4fdd\u5e02\",\"\u519c\u5730\",\"\u5317\u6d77\u9053\u30fb\u4e1c\u5317\",\"\u6cd5\u9662\",\"\u79cb\u7530\u53bf\"],\"articleSection\":[\"\u79cb\u7530\u770c\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/workbao.net\/%e7%a7%8b%e7%94%b0%e5%8e%bf%e8%83%bd%e4%bb%a3%e5%b8%82%e7%9a%84%e6%8b%8d%e5%8d%96%ef%bc%9a2-3-%e4%b8%87%e6%97%a5%e5%85%83-%e5%86%9c%e7%94%b0-1137-%e5%b9%b3%e6%96%b9%e7%b1%b3\/\",\"url\":\"https:\/\/workbao.net\/%e7%a7%8b%e7%94%b0%e5%8e%bf%e8%83%bd%e4%bb%a3%e5%b8%82%e7%9a%84%e6%8b%8d%e5%8d%96%ef%bc%9a2-3-%e4%b8%87%e6%97%a5%e5%85%83-%e5%86%9c%e7%94%b0-1137-%e5%b9%b3%e6%96%b9%e7%b1%b3\/\",\"name\":\"\u79cb\u7530\u53bf\u80fd\u4ee3\u5e02\u7684\u62cd\u5356\uff1a2.3 \u4e07\u65e5\u5143 \u519c\u7530 1137 \u5e73\u65b9\u7c73 - Japanese real estate auctioned by the court\",\"isPartOf\":{\"@id\":\"https:\/\/workbao.net\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/workbao.net\/%e7%a7%8b%e7%94%b0%e5%8e%bf%e8%83%bd%e4%bb%a3%e5%b8%82%e7%9a%84%e6%8b%8d%e5%8d%96%ef%bc%9a2-3-%e4%b8%87%e6%97%a5%e5%85%83-%e5%86%9c%e7%94%b0-1137-%e5%b9%b3%e6%96%b9%e7%b1%b3\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/workbao.net\/%e7%a7%8b%e7%94%b0%e5%8e%bf%e8%83%bd%e4%bb%a3%e5%b8%82%e7%9a%84%e6%8b%8d%e5%8d%96%ef%bc%9a2-3-%e4%b8%87%e6%97%a5%e5%85%83-%e5%86%9c%e7%94%b0-1137-%e5%b9%b3%e6%96%b9%e7%b1%b3\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/workbao.net\/wp-content\/uploads\/2024\/09\/824166a04dec1506552b6f4e43e6f443.jpg\",\"datePublished\":\"2024-09-18T16:00:00+00:00\",\"dateModified\":\"2024-09-18T16:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/workbao.net\/%e7%a7%8b%e7%94%b0%e5%8e%bf%e8%83%bd%e4%bb%a3%e5%b8%82%e7%9a%84%e6%8b%8d%e5%8d%96%ef%bc%9a2-3-%e4%b8%87%e6%97%a5%e5%85%83-%e5%86%9c%e7%94%b0-1137-%e5%b9%b3%e6%96%b9%e7%b1%b3\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/workbao.net\/%e7%a7%8b%e7%94%b0%e5%8e%bf%e8%83%bd%e4%bb%a3%e5%b8%82%e7%9a%84%e6%8b%8d%e5%8d%96%ef%bc%9a2-3-%e4%b8%87%e6%97%a5%e5%85%83-%e5%86%9c%e7%94%b0-1137-%e5%b9%b3%e6%96%b9%e7%b1%b3\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/workbao.net\/%e7%a7%8b%e7%94%b0%e5%8e%bf%e8%83%bd%e4%bb%a3%e5%b8%82%e7%9a%84%e6%8b%8d%e5%8d%96%ef%bc%9a2-3-%e4%b8%87%e6%97%a5%e5%85%83-%e5%86%9c%e7%94%b0-1137-%e5%b9%b3%e6%96%b9%e7%b1%b3\/#primaryimage\",\"url\":\"https:\/\/workbao.net\/wp-content\/uploads\/2024\/09\/824166a04dec1506552b6f4e43e6f443.jpg\",\"contentUrl\":\"https:\/\/workbao.net\/wp-content\/uploads\/2024\/09\/824166a04dec1506552b6f4e43e6f443.jpg\",\"width\":60,\"height\":45},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/workbao.net\/%e7%a7%8b%e7%94%b0%e5%8e%bf%e8%83%bd%e4%bb%a3%e5%b8%82%e7%9a%84%e6%8b%8d%e5%8d%96%ef%bc%9a2-3-%e4%b8%87%e6%97%a5%e5%85%83-%e5%86%9c%e7%94%b0-1137-%e5%b9%b3%e6%96%b9%e7%b1%b3\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u9996\u9875\",\"item\":\"https:\/\/workbao.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u79cb\u7530\u53bf\u80fd\u4ee3\u5e02\u7684\u62cd\u5356\uff1a2.3 \u4e07\u65e5\u5143 \u519c\u7530 1137 \u5e73\u65b9\u7c73\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/workbao.net\/#website\",\"url\":\"https:\/\/workbao.net\/\",\"name\":\"Japanese real estate auctioned by the court\",\"description\":\"\u4e3a\u5168\u7403\u5916\u56fd\u4eba\u6295\u8d44\u65e5\u672c\u4e0d\u52a8\u4ea7\uff0c\u63d0\u4f9b\u6cd5\u9662\uff08\u542b\u653f\u5e9c\uff09\u62cd\u5356\u623f\u4ea7\u4fe1\u606f\u3002\uff08\u63d0\u793a\uff1a1.\u6cd5\u9662\u62cd\u5356\u4ea7\u6743\u6e05\u6670\uff0c\u4ef7\u683c\u4fbf\u5b9c\uff0c\u53ef\u80fd\u6361\u6f0f\u5b9d\u8d1d\uff1b2.\u6295\u6807\u65e5\u672c\u6cd5\u62cd\u623f\uff0c\u8bf7\u9075\u5b88\u65e5\u672c\u6cd5\u9662\u76f8\u5173\u653f\u7b56\u4e0e\u89c4\u5b9a\uff09\",\"publisher\":{\"@id\":\"https:\/\/workbao.net\/#organization\"},\"alternateName\":\"\u65e5\u672c\u6cd5\u9662\u62cd\u5356\u4e0d\u52a8\u4ea7\u4fe1\u606f\u7f51\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/workbao.net\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/workbao.net\/#organization\",\"name\":\"\u51fa\u6d77\u8d22\u7ecf\u54a8\u8be2\uff08\u6df1\u5733\uff09\u6709\u9650\u516c\u53f8\",\"url\":\"https:\/\/workbao.net\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/workbao.net\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/workbao.net\/wp-content\/uploads\/2021\/07\/img2.png\",\"contentUrl\":\"https:\/\/workbao.net\/wp-content\/uploads\/2021\/07\/img2.png\",\"width\":53,\"height\":55,\"caption\":\"\u51fa\u6d77\u8d22\u7ecf\u54a8\u8be2\uff08\u6df1\u5733\uff09\u6709\u9650\u516c\u53f8\"},\"image\":{\"@id\":\"https:\/\/workbao.net\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/profile.php?id=61567565904984\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/workbao.net\/#\/schema\/person\/12758d64054b3f26a9e105241c0164dd\",\"name\":\"\u79cb\u7530\u5730\u65b9\u88c1\u5224\u6240\u672c\u5e81\",\"url\":\"https:\/\/workbao.net\/en\/author\/d9221e04b92fa8b4\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u79cb\u7530\u53bf\u80fd\u4ee3\u5e02\u7684\u62cd\u5356\uff1a2.3 \u4e07\u65e5\u5143 \u519c\u7530 1137 \u5e73\u65b9\u7c73 - Japanese real estate auctioned by the court","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/workbao.net\/en\/\u79cb\u7530\u53bf\u80fd\u4ee3\u5e02\u7684\u62cd\u5356\uff1a2-3-\u4e07\u65e5\u5143-\u519c\u7530-1137-\u5e73\u65b9\u7c73\/","og_locale":"en_US","og_type":"article","og_title":"\u79cb\u7530\u53bf\u80fd\u4ee3\u5e02\u7684\u62cd\u5356\uff1a2.3 \u4e07\u65e5\u5143 \u519c\u7530 1137 \u5e73\u65b9\u7c73","og_description":"\u7279\u522b\u9500\u552e\u671f\u95f4\u4ec5\u4e3a 2024 \u5e74 9 \u6708 19 \u65e5\uff1b\u516c\u544a\u65e5\u671f\uff1a2024 \u5e74 9 \u6708 19 \u65e5\uff1b\u7ba1\u8f96\u6cd5\u9662\uff1a\u79cb\u7530\u5730\u65b9\u88c1\u5224\u6240\u672c\u5e81\uff1b\u6848\u4ef6\u7f16\u53f7\uff1a\u4ee4\u548c04\u5e74(\u30b1)\u7b2c36\u53f7\uff1b\u8f66\u7ad9\u8ddd\u79bb\uff1a\u4e0a\u6d5c\u7ad9 77 \u5206\uff08\u7ea6 6.1 \u516c\u91cc\uff09\uff1b\u7ade\u4e70\u4fdd\u8bc1\u91d1\uff1a46 \u4e07\u65e5\u5143\u2026\u2026","og_url":"https:\/\/workbao.net\/en\/\u79cb\u7530\u53bf\u80fd\u4ee3\u5e02\u7684\u62cd\u5356\uff1a2-3-\u4e07\u65e5\u5143-\u519c\u7530-1137-\u5e73\u65b9\u7c73\/","og_site_name":"Japanese real estate auctioned by the court","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=61567565904984","article_published_time":"2024-09-18T16:00:00+00:00","og_image":[{"width":60,"height":45,"url":"https:\/\/workbao.net\/wp-content\/uploads\/2024\/09\/824166a04dec1506552b6f4e43e6f443.jpg","type":"image\/jpeg"}],"author":"\u79cb\u7530\u5730\u65b9\u88c1\u5224\u6240\u672c\u5e81","twitter_card":"summary_large_image","twitter_misc":{"Written by":"\u79cb\u7530\u5730\u65b9\u88c1\u5224\u6240\u672c\u5e81"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/workbao.net\/%e7%a7%8b%e7%94%b0%e5%8e%bf%e8%83%bd%e4%bb%a3%e5%b8%82%e7%9a%84%e6%8b%8d%e5%8d%96%ef%bc%9a2-3-%e4%b8%87%e6%97%a5%e5%85%83-%e5%86%9c%e7%94%b0-1137-%e5%b9%b3%e6%96%b9%e7%b1%b3\/#article","isPartOf":{"@id":"https:\/\/workbao.net\/%e7%a7%8b%e7%94%b0%e5%8e%bf%e8%83%bd%e4%bb%a3%e5%b8%82%e7%9a%84%e6%8b%8d%e5%8d%96%ef%bc%9a2-3-%e4%b8%87%e6%97%a5%e5%85%83-%e5%86%9c%e7%94%b0-1137-%e5%b9%b3%e6%96%b9%e7%b1%b3\/"},"author":{"name":"\u79cb\u7530\u5730\u65b9\u88c1\u5224\u6240\u672c\u5e81","@id":"https:\/\/workbao.net\/#\/schema\/person\/12758d64054b3f26a9e105241c0164dd"},"headline":"\u79cb\u7530\u53bf\u80fd\u4ee3\u5e02\u7684\u62cd\u5356\uff1a2.3 \u4e07\u65e5\u5143 \u519c\u7530 1137 \u5e73\u65b9\u7c73","datePublished":"2024-09-18T16:00:00+00:00","dateModified":"2024-09-18T16:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/workbao.net\/%e7%a7%8b%e7%94%b0%e5%8e%bf%e8%83%bd%e4%bb%a3%e5%b8%82%e7%9a%84%e6%8b%8d%e5%8d%96%ef%bc%9a2-3-%e4%b8%87%e6%97%a5%e5%85%83-%e5%86%9c%e7%94%b0-1137-%e5%b9%b3%e6%96%b9%e7%b1%b3\/"},"wordCount":6,"publisher":{"@id":"https:\/\/workbao.net\/#organization"},"image":{"@id":"https:\/\/workbao.net\/%e7%a7%8b%e7%94%b0%e5%8e%bf%e8%83%bd%e4%bb%a3%e5%b8%82%e7%9a%84%e6%8b%8d%e5%8d%96%ef%bc%9a2-3-%e4%b8%87%e6%97%a5%e5%85%83-%e5%86%9c%e7%94%b0-1137-%e5%b9%b3%e6%96%b9%e7%b1%b3\/#primaryimage"},"thumbnailUrl":"https:\/\/workbao.net\/wp-content\/uploads\/2024\/09\/824166a04dec1506552b6f4e43e6f443.jpg","keywords":["\u4ec1\u8d3a\u4fdd\u5e02","\u519c\u5730","\u5317\u6d77\u9053\u30fb\u4e1c\u5317","\u6cd5\u9662","\u79cb\u7530\u53bf"],"articleSection":["\u79cb\u7530\u770c"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/workbao.net\/%e7%a7%8b%e7%94%b0%e5%8e%bf%e8%83%bd%e4%bb%a3%e5%b8%82%e7%9a%84%e6%8b%8d%e5%8d%96%ef%bc%9a2-3-%e4%b8%87%e6%97%a5%e5%85%83-%e5%86%9c%e7%94%b0-1137-%e5%b9%b3%e6%96%b9%e7%b1%b3\/","url":"https:\/\/workbao.net\/%e7%a7%8b%e7%94%b0%e5%8e%bf%e8%83%bd%e4%bb%a3%e5%b8%82%e7%9a%84%e6%8b%8d%e5%8d%96%ef%bc%9a2-3-%e4%b8%87%e6%97%a5%e5%85%83-%e5%86%9c%e7%94%b0-1137-%e5%b9%b3%e6%96%b9%e7%b1%b3\/","name":"\u79cb\u7530\u53bf\u80fd\u4ee3\u5e02\u7684\u62cd\u5356\uff1a2.3 \u4e07\u65e5\u5143 \u519c\u7530 1137 \u5e73\u65b9\u7c73 - Japanese real estate auctioned by the court","isPartOf":{"@id":"https:\/\/workbao.net\/#website"},"primaryImageOfPage":{"@id":"https:\/\/workbao.net\/%e7%a7%8b%e7%94%b0%e5%8e%bf%e8%83%bd%e4%bb%a3%e5%b8%82%e7%9a%84%e6%8b%8d%e5%8d%96%ef%bc%9a2-3-%e4%b8%87%e6%97%a5%e5%85%83-%e5%86%9c%e7%94%b0-1137-%e5%b9%b3%e6%96%b9%e7%b1%b3\/#primaryimage"},"image":{"@id":"https:\/\/workbao.net\/%e7%a7%8b%e7%94%b0%e5%8e%bf%e8%83%bd%e4%bb%a3%e5%b8%82%e7%9a%84%e6%8b%8d%e5%8d%96%ef%bc%9a2-3-%e4%b8%87%e6%97%a5%e5%85%83-%e5%86%9c%e7%94%b0-1137-%e5%b9%b3%e6%96%b9%e7%b1%b3\/#primaryimage"},"thumbnailUrl":"https:\/\/workbao.net\/wp-content\/uploads\/2024\/09\/824166a04dec1506552b6f4e43e6f443.jpg","datePublished":"2024-09-18T16:00:00+00:00","dateModified":"2024-09-18T16:00:00+00:00","breadcrumb":{"@id":"https:\/\/workbao.net\/%e7%a7%8b%e7%94%b0%e5%8e%bf%e8%83%bd%e4%bb%a3%e5%b8%82%e7%9a%84%e6%8b%8d%e5%8d%96%ef%bc%9a2-3-%e4%b8%87%e6%97%a5%e5%85%83-%e5%86%9c%e7%94%b0-1137-%e5%b9%b3%e6%96%b9%e7%b1%b3\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/workbao.net\/%e7%a7%8b%e7%94%b0%e5%8e%bf%e8%83%bd%e4%bb%a3%e5%b8%82%e7%9a%84%e6%8b%8d%e5%8d%96%ef%bc%9a2-3-%e4%b8%87%e6%97%a5%e5%85%83-%e5%86%9c%e7%94%b0-1137-%e5%b9%b3%e6%96%b9%e7%b1%b3\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/workbao.net\/%e7%a7%8b%e7%94%b0%e5%8e%bf%e8%83%bd%e4%bb%a3%e5%b8%82%e7%9a%84%e6%8b%8d%e5%8d%96%ef%bc%9a2-3-%e4%b8%87%e6%97%a5%e5%85%83-%e5%86%9c%e7%94%b0-1137-%e5%b9%b3%e6%96%b9%e7%b1%b3\/#primaryimage","url":"https:\/\/workbao.net\/wp-content\/uploads\/2024\/09\/824166a04dec1506552b6f4e43e6f443.jpg","contentUrl":"https:\/\/workbao.net\/wp-content\/uploads\/2024\/09\/824166a04dec1506552b6f4e43e6f443.jpg","width":60,"height":45},{"@type":"BreadcrumbList","@id":"https:\/\/workbao.net\/%e7%a7%8b%e7%94%b0%e5%8e%bf%e8%83%bd%e4%bb%a3%e5%b8%82%e7%9a%84%e6%8b%8d%e5%8d%96%ef%bc%9a2-3-%e4%b8%87%e6%97%a5%e5%85%83-%e5%86%9c%e7%94%b0-1137-%e5%b9%b3%e6%96%b9%e7%b1%b3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u9996\u9875","item":"https:\/\/workbao.net\/"},{"@type":"ListItem","position":2,"name":"\u79cb\u7530\u53bf\u80fd\u4ee3\u5e02\u7684\u62cd\u5356\uff1a2.3 \u4e07\u65e5\u5143 \u519c\u7530 1137 \u5e73\u65b9\u7c73"}]},{"@type":"WebSite","@id":"https:\/\/workbao.net\/#website","url":"https:\/\/workbao.net\/","name":"Japanese real estate auctioned by the court","description":"\u4e3a\u5168\u7403\u5916\u56fd\u4eba\u6295\u8d44\u65e5\u672c\u4e0d\u52a8\u4ea7\uff0c\u63d0\u4f9b\u6cd5\u9662\uff08\u542b\u653f\u5e9c\uff09\u62cd\u5356\u623f\u4ea7\u4fe1\u606f\u3002\uff08\u63d0\u793a\uff1a1.\u6cd5\u9662\u62cd\u5356\u4ea7\u6743\u6e05\u6670\uff0c\u4ef7\u683c\u4fbf\u5b9c\uff0c\u53ef\u80fd\u6361\u6f0f\u5b9d\u8d1d\uff1b2.\u6295\u6807\u65e5\u672c\u6cd5\u62cd\u623f\uff0c\u8bf7\u9075\u5b88\u65e5\u672c\u6cd5\u9662\u76f8\u5173\u653f\u7b56\u4e0e\u89c4\u5b9a\uff09","publisher":{"@id":"https:\/\/workbao.net\/#organization"},"alternateName":"\u65e5\u672c\u6cd5\u9662\u62cd\u5356\u4e0d\u52a8\u4ea7\u4fe1\u606f\u7f51","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/workbao.net\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/workbao.net\/#organization","name":"\u51fa\u6d77\u8d22\u7ecf\u54a8\u8be2\uff08\u6df1\u5733\uff09\u6709\u9650\u516c\u53f8","url":"https:\/\/workbao.net\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/workbao.net\/#\/schema\/logo\/image\/","url":"https:\/\/workbao.net\/wp-content\/uploads\/2021\/07\/img2.png","contentUrl":"https:\/\/workbao.net\/wp-content\/uploads\/2021\/07\/img2.png","width":53,"height":55,"caption":"\u51fa\u6d77\u8d22\u7ecf\u54a8\u8be2\uff08\u6df1\u5733\uff09\u6709\u9650\u516c\u53f8"},"image":{"@id":"https:\/\/workbao.net\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61567565904984"]},{"@type":"Person","@id":"https:\/\/workbao.net\/#\/schema\/person\/12758d64054b3f26a9e105241c0164dd","name":"\u79cb\u7530\u5730\u65b9\u88c1\u5224\u6240\u672c\u5e81","url":"https:\/\/workbao.net\/en\/author\/d9221e04b92fa8b4\/"}]}},"jetpack_featured_media_url":"https:\/\/workbao.net\/wp-content\/uploads\/2024\/09\/824166a04dec1506552b6f4e43e6f443.jpg","publishpress_future_action":{"enabled":false,"date":"2026-06-25 16:24:52","action":"category","newStatus":"draft","terms":[107],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"rttpg_featured_image_url":{"full":["https:\/\/workbao.net\/wp-content\/uploads\/2024\/09\/824166a04dec1506552b6f4e43e6f443.jpg",60,45,false],"landscape":["https:\/\/workbao.net\/wp-content\/uploads\/2024\/09\/824166a04dec1506552b6f4e43e6f443.jpg",60,45,false],"portraits":["https:\/\/workbao.net\/wp-content\/uploads\/2024\/09\/824166a04dec1506552b6f4e43e6f443.jpg",60,45,false],"thumbnail":["https:\/\/workbao.net\/wp-content\/uploads\/2024\/09\/824166a04dec1506552b6f4e43e6f443.jpg",60,45,false],"medium":["https:\/\/workbao.net\/wp-content\/uploads\/2024\/09\/824166a04dec1506552b6f4e43e6f443.jpg",60,45,false],"large":["https:\/\/workbao.net\/wp-content\/uploads\/2024\/09\/824166a04dec1506552b6f4e43e6f443.jpg",60,45,false],"1536x1536":["https:\/\/workbao.net\/wp-content\/uploads\/2024\/09\/824166a04dec1506552b6f4e43e6f443.jpg",60,45,false],"2048x2048":["https:\/\/workbao.net\/wp-content\/uploads\/2024\/09\/824166a04dec1506552b6f4e43e6f443.jpg",60,45,false],"trp-custom-language-flag":["https:\/\/workbao.net\/wp-content\/uploads\/2024\/09\/824166a04dec1506552b6f4e43e6f443.jpg",16,12,false],"mynote-thumbnail":["https:\/\/workbao.net\/wp-content\/uploads\/2024\/09\/824166a04dec1506552b6f4e43e6f443.jpg",60,45,false],"mynote-medium":["https:\/\/workbao.net\/wp-content\/uploads\/2024\/09\/824166a04dec1506552b6f4e43e6f443.jpg",60,45,false],"tenweb_optimizer_mobile":["https:\/\/workbao.net\/wp-content\/uploads\/2024\/09\/824166a04dec1506552b6f4e43e6f443.jpg",60,45,false],"tenweb_optimizer_tablet":["https:\/\/workbao.net\/wp-content\/uploads\/2024\/09\/824166a04dec1506552b6f4e43e6f443.jpg",60,45,false]},"rttpg_author":{"display_name":"\u79cb\u7530\u5730\u65b9\u88c1\u5224\u6240\u672c\u5e81","author_link":"https:\/\/workbao.net\/en\/author\/d9221e04b92fa8b4\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/workbao.net\/en\/topics\/qitachengshi\/\u79cb\u7530\u770c\/\" rel=\"tag\">\u79cb\u7530\u770c<\/a>","rttpg_excerpt":"\u7279\u522b\u9500\u552e\u671f\u95f4\u4ec5\u4e3a 2024 \u5e74 9 \u6708 19 \u65e5\uff1b\u516c\u544a\u65e5\u671f\uff1a2024 \u5e74 9 \u6708 19 \u65e5\uff1b\u7ba1\u8f96\u6cd5\u9662\uff1a\u79cb\u7530\u5730\u65b9&hellip;","_links":{"self":[{"href":"https:\/\/workbao.net\/en\/wp-json\/wp\/v2\/posts\/24886","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/workbao.net\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/workbao.net\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/workbao.net\/en\/wp-json\/wp\/v2\/users\/310"}],"replies":[{"embeddable":true,"href":"https:\/\/workbao.net\/en\/wp-json\/wp\/v2\/comments?post=24886"}],"version-history":[{"count":0,"href":"https:\/\/workbao.net\/en\/wp-json\/wp\/v2\/posts\/24886\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/workbao.net\/en\/wp-json\/wp\/v2\/media\/24887"}],"wp:attachment":[{"href":"https:\/\/workbao.net\/en\/wp-json\/wp\/v2\/media?parent=24886"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/workbao.net\/en\/wp-json\/wp\/v2\/categories?post=24886"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/workbao.net\/en\/wp-json\/wp\/v2\/tags?post=24886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}