{"id":20178,"date":"2024-08-13T16:00:00","date_gmt":"2024-08-13T16:00:00","guid":{"rendered":"https:\/\/workbao.net\/archives\/20178"},"modified":"2024-08-13T16:00:00","modified_gmt":"2024-08-13T16:00:00","slug":"%e7%a5%9e%e5%a5%88%e5%b7%9d%e5%8e%bf%e5%b7%9d%e5%b4%8e%e5%b8%82%e4%b8%ad%e5%8e%9f%e5%8c%ba%e7%9a%84%e6%8b%8d%e5%8d%96%ef%bc%9a2434-%e4%b8%87%e6%97%a5%e5%85%83-%e4%b8%80%e6%88%b7%e5%bb%ba-110-%e5%b9%b3","status":"publish","type":"post","link":"https:\/\/workbao.net\/fr\/\u795e\u5948\u5ddd\u53bf\u5ddd\u5d0e\u5e02\u4e2d\u539f\u533a\u7684\u62cd\u5356\uff1a2434-\u4e07\u65e5\u5143-\u4e00\u6237\u5efa-110-\u5e73\/","title":{"rendered":"Vente aux ench\u00e8res \u00e0 Nakahara-ku, ville de Kawasaki, pr\u00e9fecture de Kanagawa\u00a0: 24,34 millions de yens pour une maison de 110 m\u00e8tres carr\u00e9s"},"content":{"rendered":"<div class=\"container1\">\n<img decoding=\"async\" src=\"https:\/\/storage.xn--55q36pba3495a.com\/assets\/photo\/tmb\/253281-1.jpg\" class=\"mySlides fade1\"><img decoding=\"async\" src=\"https:\/\/storage.xn--55q36pba3495a.com\/assets\/photo\/tmb\/253281-2.jpg\" class=\"mySlides fade1\"><img decoding=\"async\" src=\"https:\/\/storage.xn--55q36pba3495a.com\/assets\/photo\/tmb\/253281-3.jpg\" class=\"mySlides fade1\"><img decoding=\"async\" src=\"https:\/\/storage.xn--55q36pba3495a.com\/assets\/photo\/tmb\/253281-4.jpg\" class=\"mySlides fade1\"><img decoding=\"async\" src=\"https:\/\/storage.xn--55q36pba3495a.com\/assets\/photo\/tmb\/253281-5.jpg\" class=\"mySlides fade1\"><img decoding=\"async\" src=\"https:\/\/storage.xn--55q36pba3495a.com\/assets\/photo\/tmb\/253281-6.jpg\" class=\"mySlides fade1\"><img decoding=\"async\" src=\"https:\/\/storage.xn--55q36pba3495a.com\/assets\/photo\/tmb\/253281-7.jpg\" class=\"mySlides fade1\"><img decoding=\"async\" src=\"https:\/\/storage.xn--55q36pba3495a.com\/assets\/photo\/tmb\/253281-8.jpg\" class=\"mySlides fade1\"><a class=\"prev\">&#10094;<\/a><a class=\"next\">&#10095;<\/a><\/p>\n<div class=\"thumbnails\">\n<div class=\"thumbnail\" onclick=\"currentSlide(1)\"><img decoding=\"async\" src=\"https:\/\/storage.xn--55q36pba3495a.com\/assets\/photo\/tmb\/253281-1.jpg\"><\/div>\n<div class=\"thumbnail\" onclick=\"currentSlide(2)\"><img decoding=\"async\" src=\"https:\/\/storage.xn--55q36pba3495a.com\/assets\/photo\/tmb\/253281-2.jpg\"><\/div>\n<div class=\"thumbnail\" onclick=\"currentSlide(3)\"><img decoding=\"async\" src=\"https:\/\/storage.xn--55q36pba3495a.com\/assets\/photo\/tmb\/253281-3.jpg\"><\/div>\n<div class=\"thumbnail\" onclick=\"currentSlide(4)\"><img decoding=\"async\" src=\"https:\/\/storage.xn--55q36pba3495a.com\/assets\/photo\/tmb\/253281-4.jpg\"><\/div>\n<div class=\"thumbnail\" onclick=\"currentSlide(5)\"><img decoding=\"async\" src=\"https:\/\/storage.xn--55q36pba3495a.com\/assets\/photo\/tmb\/253281-5.jpg\"><\/div>\n<div class=\"thumbnail\" onclick=\"currentSlide(6)\"><img decoding=\"async\" src=\"https:\/\/storage.xn--55q36pba3495a.com\/assets\/photo\/tmb\/253281-6.jpg\"><\/div>\n<div class=\"thumbnail\" onclick=\"currentSlide(7)\"><img decoding=\"async\" src=\"https:\/\/storage.xn--55q36pba3495a.com\/assets\/photo\/tmb\/253281-7.jpg\"><\/div>\n<div class=\"thumbnail\" onclick=\"currentSlide(8)\"><img decoding=\"async\" src=\"https:\/\/storage.xn--55q36pba3495a.com\/assets\/photo\/tmb\/253281-8.jpg\"><\/div>\n<\/div>\n<\/div>\n<p>;<a href=\"https:\/\/maps.apple.com\/?ll=35.559944,139.641812&amp;q=\u51c6\u786e\u4f4d\u7f6e\" target=\"_blank\" rel=\"noopener\">Ouvrez Apple Maps pour afficher l&#039;emplacement exact du projet &gt;&gt;<\/a>;<\/p>\n<h2>p\u00e9riode d&#039;ench\u00e8res<label for=\"bidformat-modal\" class=\"vlink\" title=\"La diff\u00e9rence entre les ench\u00e8res p\u00e9riodiques et les ventes sp\u00e9ciales\"><sup><i class=\"icon-help\"><\/i><\/sup><\/label><span class=\"normal\"> (premi\u00e8re version) <\/span><\/h2>\n<dl class=\"props\">\n<dt class=\"dtqq\">\n  Tribunal juridictionnel\n <\/dt>\n<dd class=\"ddqq\">\n  Tribunal de district de Yokohama, succursale de Kawasaki\n <\/dd>\n<dt class=\"dtqq\">\n  num\u00e9ro de dossier\n <\/dt>\n<dd class=\"ddqq\">\n  \u4ee4\u548c 05 \u5e74(\u30cc)\u7b2c 50 \u53f7\n <\/dd>\n<dt class=\"dtqq\">\n  prix de base de vente\n <\/dt>\n<dd class=\"ddqq\">\n  24,340,000 \u65e5\u5143\n <\/dd>\n<dt class=\"dtqq\">\n  Montant du d\u00e9p\u00f4t pour la demande d&#039;achat\n <\/dt>\n<dd class=\"ddqq\">\n  4,868,000 \u65e5\u5143\n <\/dd>\n<dt class=\"dtqq\">\n  Prix disponible\n <\/dt>\n<dd class=\"ddqq\">\n  19,472,000 \u65e5\u5143\n <\/dd>\n<\/dl>\n<h2>R\u00e9sum\u00e9 de l&#039;objet<\/h2>\n<dl class=\"props\">\n<dt class=\"dtqq\">\n  emplacement\n <\/dt>\n<dd class=\"ddqq\">\n  \u795e\u5948\u5ddd\u53bf\u5ddd\u5d0e\u5e02\u4e2d\u539f\u533a\u4e95\u7530\u4e8c\u4e01\u76ee 1332 \u756a\u5730 6\n <\/dd>\n<dt class=\"dtqq\">\n  indication de r\u00e9sidence\n <\/dt>\n<dd class=\"ddqq\">\n  \u795e\u5948\u5ddd\u53bf\u5ddd\u5d0e\u5e02\u4e2d\u539f\u533a\u4e95\u7530\u4e8c\u4e01\u76ee 17 \u756a 25 \u53f7\n <\/dd>\n<dt class=\"dtqq\">\n  \u00c9valuation du transport\n <\/dt>\n<dd class=\"ddqq\">\n  \u4e1c\u6025\u4e1c\u6a2a\u7ebf\u300c\u65e5\u5409\u300d\u7ad9 \u897f\u5317\u65b9 \u7ea6 1100m(\u9053\u8def\u8ddd\u79bb)<br \/>\n  <br \/>\u300c\u5143\u4f4f\u5409\u300d\u7ad9 \u897f\u5357\u65b9 \u7ea6 1600m  <br \/>\u6700\u8fd1\u5df4\u58eb\u7ad9\u300c\u4e95\u7530\u5742\u300d\u6b65\u884c\u7ea6 4 \u5206\u949f\n <\/dd>\n<dt class=\"dtqq\">\n  Transport de r\u00e9f\u00e9rence\n <\/dt>\n<dd class=\"ddqq\">\n  \u4e1c\u6025\u76ee\u9ed1\u7ebf \u65e5\u5409\u7ad9 \u897f\u5317\u65b9 0.82km  <br \/>0,87 km au nord-ouest de la gare de Hiyoshi sur la ligne 4 du train \u00e0 grande vitesse de la ville de Yokohama <\/dd>\n<dt class=\"dtqq\">\n  Superficie totale du b\u00e2timent\n <\/dt>\n<dd class=\"ddqq\">\n  109.53m  <sup>2<\/sup> (33,1 m\u00e8tres carr\u00e9s)\n <\/dd>\n<dt class=\"dtqq\">\n  Superficie du terrain (total)\n <\/dt>\n<dd class=\"ddqq\">\n  162.72m  <sup>2<\/sup> (49.2 \u576a)\n <\/dd>\n<dt class=\"dtqq\">\n  Type de maison\n <\/dt>\n<dd class=\"ddqq\">\n  4LDK\n <\/dd>\n<dt class=\"dtqq\">\n  taper\n <\/dt>\n<dd class=\"ddqq\">\n  R\u00e9sidentiel\n <\/dd>\n<dt class=\"dtqq\">\n  Domaine d&#039;application\n <\/dt>\n<dd class=\"ddqq\">\n  Le premier type de zone d\u00e9di\u00e9e aux zones r\u00e9sidentielles de moyenne et grande hauteur (des appartements ou des immeubles collectifs peuvent \u00eatre construits)\n <\/dd>\n<dt class=\"dtqq\">\n  Num\u00e9ro d&#039;objet\n <\/dt>\n<dd class=\"ddqq\">\n<ul class=\"prop-kinds\">\n<li>1 \u00e0 3. Atterrir<\/li>\n<li>4. B\u00e2timent (propri\u00e9t\u00e9)<\/li>\n<\/ul>\n<\/dd>\n<\/dl>\n<h2>D\u00e9tails de l&#039;objet<\/h2>\n<dl class=\"props\">\n<dt class=\"dtqq\">\n  Num\u00e9ro d&#039;objet\n <\/dt>\n<dd class=\"ddqq\">\n  1\n <\/dd>\n<dt class=\"dtqq\">\n  cat\u00e9gorie\n <\/dt>\n<dd class=\"ddqq\">\n  atterrir\n <\/dd>\n<dt class=\"dtqq\">\n  emplacement\n <\/dt>\n<dd class=\"ddqq\">\n  \u5ddd\u5d0e\u5e02\u4e2d\u539f\u533a\u4e95\u7530\u4e8c\u4e01\u76ee 1332 \u756a 6\n <\/dd>\n<dt class=\"dtqq\">\n  Localisation (inscription)\n <\/dt>\n<dd class=\"ddqq\">\n  lieu d&#039;habitation\n <\/dd>\n<dt class=\"dtqq\">\n  Superficie du terrain (enregistrement)\n <\/dt>\n<dd class=\"ddqq\">\n  125.36m  <sup>2<\/sup> (37.9 \u576a)\n <\/dd>\n<dt class=\"dtqq\">\n  Domaine d&#039;application\n <\/dt>\n<dd class=\"ddqq\">\n  Le premier type de zone d\u00e9di\u00e9e aux zones r\u00e9sidentielles de moyenne et grande hauteur (des appartements ou des immeubles collectifs peuvent \u00eatre construits)\n <\/dd>\n<dt class=\"dtqq\">\n  Taux de couverture des b\u00e2timents\n <\/dt>\n<dd class=\"ddqq\">\n  60%\n <\/dd>\n<dt class=\"dtqq\">\n  Rapport surface au sol\n <\/dt>\n<dd class=\"ddqq\">\n  200%\n <\/dd>\n<\/dl>\n<dl class=\"props\">\n<dt class=\"dtqq\">\n  Num\u00e9ro d&#039;objet\n <\/dt>\n<dd class=\"ddqq\">\n  2\n <\/dd>\n<dt class=\"dtqq\">\n  cat\u00e9gorie\n <\/dt>\n<dd class=\"ddqq\">\n  part de terrain \u00e0 vendre\n <\/dd>\n<dt class=\"dtqq\">\n  emplacement\n <\/dt>\n<dd class=\"ddqq\">\n  \u5ddd\u5d0e\u5e02\u4e2d\u539f\u533a\u4e95\u7530\u4e8c\u4e01\u76ee 1332 \u756a 7\n <\/dd>\n<dt class=\"dtqq\">\n  Localisation (inscription)\n <\/dt>\n<dd class=\"ddqq\">\n  voie publique\n <\/dd>\n<dt class=\"dtqq\">\n  Superficie du terrain (enregistrement)\n <\/dt>\n<dd class=\"ddqq\">\n  17m  <sup>2<\/sup> (ping 5.1)\n <\/dd>\n<dt class=\"dtqq\">\n  Partager\n <\/dt>\n<dd class=\"ddqq\">\n  une moiti\u00e9\n <\/dd>\n<\/dl>\n<dl class=\"props\">\n<dt class=\"dtqq\">\n  Num\u00e9ro d&#039;objet\n <\/dt>\n<dd class=\"ddqq\">\n  3\n <\/dd>\n<dt class=\"dtqq\">\n  cat\u00e9gorie\n <\/dt>\n<dd class=\"ddqq\">\n  atterrir\n <\/dd>\n<dt class=\"dtqq\">\n  emplacement\n <\/dt>\n<dd class=\"ddqq\">\n  \u5ddd\u5d0e\u5e02\u4e2d\u539f\u533a\u4e95\u7530\u4e8c\u4e01\u76ee 1332 \u756a 9\n <\/dd>\n<dt class=\"dtqq\">\n  Localisation (inscription)\n <\/dt>\n<dd class=\"ddqq\">\n  lieu d&#039;habitation\n <\/dd>\n<dt class=\"dtqq\">\n  Superficie du terrain (enregistrement)\n <\/dt>\n<dd class=\"ddqq\">\n  28.86m  <sup>2<\/sup> (8,7 m\u00e8tres carr\u00e9s)\n <\/dd>\n<\/dl>\n<dl class=\"props\">\n<dt class=\"dtqq\">\n  Num\u00e9ro d&#039;objet\n <\/dt>\n<dd class=\"ddqq\">\n  4\n <\/dd>\n<dt class=\"dtqq\">\n  cat\u00e9gorie\n <\/dt>\n<dd class=\"ddqq\">\n  b\u00e2timent\n <\/dd>\n<dt class=\"dtqq\">\n  emplacement\n <\/dt>\n<dd class=\"ddqq\">\n  \u5ddd\u5d0e\u5e02\u4e2d\u539f\u533a\u4e95\u7530\u4e8c\u4e01\u76ee 1332 \u756a\u5730 6\n <\/dd>\n<dt class=\"dtqq\">\n  num\u00e9ro de maison\n <\/dt>\n<dd class=\"ddqq\">\n  1332 \u756a 6\n <\/dd>\n<dt class=\"dtqq\">\n  Type (enregistrement)\n <\/dt>\n<dd class=\"ddqq\">\n  R\u00e9sidentiel\n <\/dd>\n<dt class=\"dtqq\">\n  Structure (inscription)\n <\/dt>\n<dd class=\"ddqq\">\n  Immeuble de 2 \u00e9tages avec toit en ardoise en bois\n <\/dd>\n<dt class=\"dtqq\">\n  Superficie du b\u00e2timent (enregistr\u00e9)\n <\/dt>\n<dd class=\"ddqq\">\n  1 \u5c42 58.58m  <sup>2<\/sup> (17,7 m\u00e8tres carr\u00e9s)<br \/>\n  <br \/>2 \u5c42 45.95m  <sup>2<\/sup> (13.9 \u576a)\n <\/dd>\n<dt class=\"dtqq\">\n  Superficie du b\u00e2timent (situation actuelle)\n <\/dt>\n<dd class=\"ddqq\">\n  1 \u5c42 58.58m  <sup>2<\/sup> (17,7 m\u00e8tres carr\u00e9s)<br \/>\n  <br \/>2 \u5c42 \u7ea6 50.95m  <sup>2<\/sup> (15,4 m\u00e8tres carr\u00e9s)\n <\/dd>\n<dt class=\"dtqq\">\n  Type de maison\n <\/dt>\n<dd class=\"ddqq\">\n  4LDK\n <\/dd>\n<dt class=\"dtqq\">\n  droits d&#039;utilisation des terres\n <\/dt>\n<dd class=\"ddqq\">\n  possession\n <\/dd>\n<dt class=\"dtqq\">\n  possesseur\n <\/dt>\n<dd class=\"ddqq\">\n  D\u00e9biteur \u00b7 Propri\u00e9taire\n <\/dd>\n<dt class=\"dtqq\">\n  Ann\u00e9e de construction\n <\/dt>\n<dd class=\"ddqq\">\n  \u5e73\u6210 15 \u5e74 5 \u6708 (2003 \u5e74\u00b7\u5efa\u9020 21 \u5e74)\n <\/dd>\n<\/dl>\n<dl class=\"props full\">\n<dt class=\"dtqq\">\n  Choses \u00e0 noter\n <\/dt>\n<dd class=\"ddqq\">\n   \u5173\u4e8e\u672c\u8be6\u7ec6\u4fe1\u606f\u753b\u9762\u7684\u5185\u5bb9\uff0c\u8bf7\u52a1\u5fc5\u4e0b\u8f7d\u7269\u4ef6\u8d44\u6599 3 \u4ef6\u5957 (\u7269\u4ef6\u660e\u7ec6\u4e66\u3001\u73b0\u72b6\u8c03\u67e5\u62a5\u544a\u4e66\u53ca\u8bc4\u4f30\u4e66\u7b49)\u8fdb\u884c\u786e\u8ba4\uff08\u5b58\u5728\u6c11\u4e8b\u6267\u884c\u6cd5 63 \u6761 2 \u9879 1 \u53f7\u7684\u7533\u62a5\u7b49\u60c5\u51b5\uff09\u3002\u4ece\u672c\u7cfb\u7edf\u4e0b\u8f7d\u7684\u300c\u73b0\u72b6\u8c03\u67e5\u62a5\u544a\u4e66\u300d\u53ca\u300c\u8bc4\u4f30\u4e66\u300d\u4e2d\u5f15\u7528\u7684\u7167\u7247\u3001\u8d44\u6599\u53ca\u56fe\u7eb8\uff0c\u5728\u672c\u7cfb\u7edf\u4e0a\u53ef\u80fd\u672a\u9644\u52a0\u3002\n <\/dd>\n<\/dl>\n<h2>calendrier des ventes<\/h2>\n<dl class=\"props\">\n<dt class=\"dtqq\">\n  Date de r\u00e9alisation de la vente\n <\/dt>\n<dd class=\"ddqq\">\n  26 juillet 2024 (vendredi)\n <\/dd>\n<dt class=\"dtqq\">\n  Jour d&#039;annonce\n <\/dt>\n<dd class=\"ddqq\">\n  14 ao\u00fbt 2024 (mercredi)\n <\/dd>\n<dt class=\"dtqq\">\n  Date de d\u00e9but de navigation\n <\/dt>\n<dd class=\"ddqq\">\n  14 ao\u00fbt 2024 (mercredi)\n <\/dd>\n<dt class=\"dtqq\">\n  p\u00e9riode d&#039;ench\u00e8res\n <\/dt>\n<dd class=\"ddqq\">\n  2024 \u5e74 8 \u6708 28 \u65e5(\u661f\u671f\u4e09)\u81f3 9 \u6708 4 \u65e5(\u661f\u671f\u4e09)\n <\/dd>\n<dt class=\"dtqq\">\n  Jour d&#039;ouverture des offres\n <\/dt>\n<dd class=\"ddqq\">\n  11 septembre 2024 (mercredi)\n <\/dd>\n<dt class=\"dtqq\">\n  p\u00e9riode de vente sp\u00e9ciale\n <\/dt>\n<dd class=\"ddqq\">\n  Seulement le 19 septembre 2024 (jeudi)\n <\/dd>\n<dt class=\"dtqq\">\n  date de d\u00e9cision de vente\n <\/dt>\n<dd class=\"ddqq\">\n  1er octobre 2024 (mardi)\n <\/dd>\n<dt class=\"dtqq\">\n  Date de confirmation\n <\/dt>\n<dd class=\"ddqq\">\n  9 octobre 2024 (mercredi)\n <\/dd>\n<dt class=\"dtqq\">\n  \u00c9tat\n <\/dt>\n<dd class=\"ddqq\">\n  Consultable\n <\/dd>\n<dt class=\"dtqq\">\n  calendrier\n <\/dt>\n<dd class=\"ddqq\">\n  Calendrier annuel des ventes\/Tribunal de district de Yokohama, succursale de Kawasaki\n <\/dd>\n<\/dl>\n<p>Source\u00a0: informations sur les articles de vente aux ench\u00e8res immobili\u00e8res du tribunal BIT<br \/>\n<i class=\"icon-link-ext\"><\/i><\/p>","protected":false},"excerpt":{"rendered":"<p>P\u00e9riode d&#039;appel d&#039;offres : du 28 ao\u00fbt au 4 septembre 2024 ; Date de l&#039;annonce : 14 ao\u00fbt 2024 ; Tribunal juridictionnel : Tribunal du district de Yokohama, succursale de Kawasaki ; Num\u00e9ro de dossier : Reiwa 05 (\u30cc) n\u00b0 50 Distance de la gare : 11 minutes de la gare de Hiyoshi ; 820 m\u00e8tres)\u00a0; D\u00e9p\u00f4t d&#039;appel d&#039;offres\u00a0: 4,868 millions de yens...<\/p>","protected":false},"author":120,"featured_media":20179,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[323],"tags":[330,200,1163,173,219],"class_list":["post-20178","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hengbin","tag-330","tag-200","tag-1163","tag-173","tag-219"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.0 (Yoast SEO v24.0) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u795e\u5948\u5ddd\u53bf\u5ddd\u5d0e\u5e02\u4e2d\u539f\u533a\u7684\u62cd\u5356\uff1a2434 \u4e07\u65e5\u5143 \u4e00\u6237\u5efa 110 \u5e73\u65b9\u7c73 - Japanese real estate auctioned by the court<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/workbao.net\/fr\/\u795e\u5948\u5ddd\u53bf\u5ddd\u5d0e\u5e02\u4e2d\u539f\u533a\u7684\u62cd\u5356\uff1a2434-\u4e07\u65e5\u5143-\u4e00\u6237\u5efa-110-\u5e73\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u795e\u5948\u5ddd\u53bf\u5ddd\u5d0e\u5e02\u4e2d\u539f\u533a\u7684\u62cd\u5356\uff1a2434 \u4e07\u65e5\u5143 \u4e00\u6237\u5efa 110 \u5e73\u65b9\u7c73\" \/>\n<meta property=\"og:description\" content=\"\u6295\u6807\u65f6\u95f4\uff1a2024 \u5e74 8 \u6708 28 \u65e5\u81f3 9 \u6708 4 \u65e5\uff1b\u516c\u544a\u65e5\u671f\uff1a2024 \u5e74 8 \u6708 14 \u65e5\uff1b\u7ba1\u8f96\u6cd5\u9662\uff1a\u6a2a\u6ee8\u5730\u65b9\u6cd5\u9662\u5ddd\u5d0e\u652f\u90e8\uff1b\u6848\u4ef6\u7f16\u53f7\uff1a\u4ee4\u548c05\u5e74(\u30cc)\u7b2c50\u53f7\uff1b\u8f66\u7ad9\u8ddd\u79bb\uff1a\u65e5\u5409\u7ad9 11 \u5206\u949f\uff08\u7ea6 820 \u7c73\uff09\uff1b\u7ade\u4e70\u4fdd\u8bc1\u91d1\uff1a486.8 \u4e07\u65e5\u5143\u2026\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/workbao.net\/fr\/\u795e\u5948\u5ddd\u53bf\u5ddd\u5d0e\u5e02\u4e2d\u539f\u533a\u7684\u62cd\u5356\uff1a2434-\u4e07\u65e5\u5143-\u4e00\u6237\u5efa-110-\u5e73\/\" \/>\n<meta property=\"og:site_name\" content=\"Japanese real estate auctioned by the court\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=61567565904984\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-13T16:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/workbao.net\/wp-content\/uploads\/2024\/08\/e04ca3843f68c7e2c113b89c0f704778.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"\u6a2a\u6ee8\u5730\u65b9\u6cd5\u9662\u5ddd\u5d0e\u652f\u90e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u6a2a\u6ee8\u5730\u65b9\u6cd5\u9662\u5ddd\u5d0e\u652f\u90e8\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/workbao.net\/zh\/%e7%a5%9e%e5%a5%88%e5%b7%9d%e5%8e%bf%e5%b7%9d%e5%b4%8e%e5%b8%82%e4%b8%ad%e5%8e%9f%e5%8c%ba%e7%9a%84%e6%8b%8d%e5%8d%96%ef%bc%9a2434-%e4%b8%87%e6%97%a5%e5%85%83-%e4%b8%80%e6%88%b7%e5%bb%ba-110-%e5%b9%b3\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/workbao.net\/zh\/%e7%a5%9e%e5%a5%88%e5%b7%9d%e5%8e%bf%e5%b7%9d%e5%b4%8e%e5%b8%82%e4%b8%ad%e5%8e%9f%e5%8c%ba%e7%9a%84%e6%8b%8d%e5%8d%96%ef%bc%9a2434-%e4%b8%87%e6%97%a5%e5%85%83-%e4%b8%80%e6%88%b7%e5%bb%ba-110-%e5%b9%b3\/\"},\"author\":{\"name\":\"\u6a2a\u6ee8\u5730\u65b9\u6cd5\u9662\u5ddd\u5d0e\u652f\u90e8\",\"@id\":\"https:\/\/workbao.net\/#\/schema\/person\/0e790bad3408958a94de3d4e3da0619f\"},\"headline\":\"\u795e\u5948\u5ddd\u53bf\u5ddd\u5d0e\u5e02\u4e2d\u539f\u533a\u7684\u62cd\u5356\uff1a2434 \u4e07\u65e5\u5143 \u4e00\u6237\u5efa 110 \u5e73\u65b9\u7c73\",\"datePublished\":\"2024-08-13T16:00:00+00:00\",\"dateModified\":\"2024-08-13T16:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/workbao.net\/zh\/%e7%a5%9e%e5%a5%88%e5%b7%9d%e5%8e%bf%e5%b7%9d%e5%b4%8e%e5%b8%82%e4%b8%ad%e5%8e%9f%e5%8c%ba%e7%9a%84%e6%8b%8d%e5%8d%96%ef%bc%9a2434-%e4%b8%87%e6%97%a5%e5%85%83-%e4%b8%80%e6%88%b7%e5%bb%ba-110-%e5%b9%b3\/\"},\"wordCount\":18,\"publisher\":{\"@id\":\"https:\/\/workbao.net\/#organization\"},\"image\":{\"@id\":\"https:\/\/workbao.net\/zh\/%e7%a5%9e%e5%a5%88%e5%b7%9d%e5%8e%bf%e5%b7%9d%e5%b4%8e%e5%b8%82%e4%b8%ad%e5%8e%9f%e5%8c%ba%e7%9a%84%e6%8b%8d%e5%8d%96%ef%bc%9a2434-%e4%b8%87%e6%97%a5%e5%85%83-%e4%b8%80%e6%88%b7%e5%bb%ba-110-%e5%b9%b3\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/workbao.net\/wp-content\/uploads\/2024\/08\/e04ca3843f68c7e2c113b89c0f704778.jpg\",\"keywords\":[\"\u4e00\u6237\u5efa\",\"\u5173\u4e1c\u5730\u65b9\",\"\u5ddd\u5d0e\u5e02\u4e2d\u539f\u533a\",\"\u6cd5\u9662\",\"\u795e\u5948\u5ddd\u53bf\"],\"articleSection\":[\"\u6a2a\u6ee8\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/workbao.net\/zh\/%e7%a5%9e%e5%a5%88%e5%b7%9d%e5%8e%bf%e5%b7%9d%e5%b4%8e%e5%b8%82%e4%b8%ad%e5%8e%9f%e5%8c%ba%e7%9a%84%e6%8b%8d%e5%8d%96%ef%bc%9a2434-%e4%b8%87%e6%97%a5%e5%85%83-%e4%b8%80%e6%88%b7%e5%bb%ba-110-%e5%b9%b3\/\",\"url\":\"https:\/\/workbao.net\/zh\/%e7%a5%9e%e5%a5%88%e5%b7%9d%e5%8e%bf%e5%b7%9d%e5%b4%8e%e5%b8%82%e4%b8%ad%e5%8e%9f%e5%8c%ba%e7%9a%84%e6%8b%8d%e5%8d%96%ef%bc%9a2434-%e4%b8%87%e6%97%a5%e5%85%83-%e4%b8%80%e6%88%b7%e5%bb%ba-110-%e5%b9%b3\/\",\"name\":\"\u795e\u5948\u5ddd\u53bf\u5ddd\u5d0e\u5e02\u4e2d\u539f\u533a\u7684\u62cd\u5356\uff1a2434 \u4e07\u65e5\u5143 \u4e00\u6237\u5efa 110 \u5e73\u65b9\u7c73 - Japanese real estate auctioned by the court\",\"isPartOf\":{\"@id\":\"https:\/\/workbao.net\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/workbao.net\/zh\/%e7%a5%9e%e5%a5%88%e5%b7%9d%e5%8e%bf%e5%b7%9d%e5%b4%8e%e5%b8%82%e4%b8%ad%e5%8e%9f%e5%8c%ba%e7%9a%84%e6%8b%8d%e5%8d%96%ef%bc%9a2434-%e4%b8%87%e6%97%a5%e5%85%83-%e4%b8%80%e6%88%b7%e5%bb%ba-110-%e5%b9%b3\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/workbao.net\/zh\/%e7%a5%9e%e5%a5%88%e5%b7%9d%e5%8e%bf%e5%b7%9d%e5%b4%8e%e5%b8%82%e4%b8%ad%e5%8e%9f%e5%8c%ba%e7%9a%84%e6%8b%8d%e5%8d%96%ef%bc%9a2434-%e4%b8%87%e6%97%a5%e5%85%83-%e4%b8%80%e6%88%b7%e5%bb%ba-110-%e5%b9%b3\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/workbao.net\/wp-content\/uploads\/2024\/08\/e04ca3843f68c7e2c113b89c0f704778.jpg\",\"datePublished\":\"2024-08-13T16:00:00+00:00\",\"dateModified\":\"2024-08-13T16:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/workbao.net\/zh\/%e7%a5%9e%e5%a5%88%e5%b7%9d%e5%8e%bf%e5%b7%9d%e5%b4%8e%e5%b8%82%e4%b8%ad%e5%8e%9f%e5%8c%ba%e7%9a%84%e6%8b%8d%e5%8d%96%ef%bc%9a2434-%e4%b8%87%e6%97%a5%e5%85%83-%e4%b8%80%e6%88%b7%e5%bb%ba-110-%e5%b9%b3\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/workbao.net\/zh\/%e7%a5%9e%e5%a5%88%e5%b7%9d%e5%8e%bf%e5%b7%9d%e5%b4%8e%e5%b8%82%e4%b8%ad%e5%8e%9f%e5%8c%ba%e7%9a%84%e6%8b%8d%e5%8d%96%ef%bc%9a2434-%e4%b8%87%e6%97%a5%e5%85%83-%e4%b8%80%e6%88%b7%e5%bb%ba-110-%e5%b9%b3\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/workbao.net\/zh\/%e7%a5%9e%e5%a5%88%e5%b7%9d%e5%8e%bf%e5%b7%9d%e5%b4%8e%e5%b8%82%e4%b8%ad%e5%8e%9f%e5%8c%ba%e7%9a%84%e6%8b%8d%e5%8d%96%ef%bc%9a2434-%e4%b8%87%e6%97%a5%e5%85%83-%e4%b8%80%e6%88%b7%e5%bb%ba-110-%e5%b9%b3\/#primaryimage\",\"url\":\"https:\/\/workbao.net\/wp-content\/uploads\/2024\/08\/e04ca3843f68c7e2c113b89c0f704778.jpg\",\"contentUrl\":\"https:\/\/workbao.net\/wp-content\/uploads\/2024\/08\/e04ca3843f68c7e2c113b89c0f704778.jpg\",\"width\":400,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/workbao.net\/zh\/%e7%a5%9e%e5%a5%88%e5%b7%9d%e5%8e%bf%e5%b7%9d%e5%b4%8e%e5%b8%82%e4%b8%ad%e5%8e%9f%e5%8c%ba%e7%9a%84%e6%8b%8d%e5%8d%96%ef%bc%9a2434-%e4%b8%87%e6%97%a5%e5%85%83-%e4%b8%80%e6%88%b7%e5%bb%ba-110-%e5%b9%b3\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u9996\u9875\",\"item\":\"https:\/\/workbao.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u795e\u5948\u5ddd\u53bf\u5ddd\u5d0e\u5e02\u4e2d\u539f\u533a\u7684\u62cd\u5356\uff1a2434 \u4e07\u65e5\u5143 \u4e00\u6237\u5efa 110 \u5e73\u65b9\u7c73\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/workbao.net\/#website\",\"url\":\"https:\/\/workbao.net\/\",\"name\":\"Japanese real estate auctioned by the court\",\"description\":\"\u4e3a\u5168\u7403\u5916\u56fd\u4eba\u6295\u8d44\u65e5\u672c\u4e0d\u52a8\u4ea7\uff0c\u63d0\u4f9b\u6cd5\u9662\uff08\u542b\u653f\u5e9c\uff09\u62cd\u5356\u623f\u4ea7\u4fe1\u606f\u3002\uff08\u63d0\u793a\uff1a1.\u6cd5\u9662\u62cd\u5356\u4ea7\u6743\u6e05\u6670\uff0c\u4ef7\u683c\u4fbf\u5b9c\uff0c\u53ef\u80fd\u6361\u6f0f\u5b9d\u8d1d\uff1b2.\u6295\u6807\u65e5\u672c\u6cd5\u62cd\u623f\uff0c\u8bf7\u9075\u5b88\u65e5\u672c\u6cd5\u9662\u76f8\u5173\u653f\u7b56\u4e0e\u89c4\u5b9a\uff09\",\"publisher\":{\"@id\":\"https:\/\/workbao.net\/#organization\"},\"alternateName\":\"\u65e5\u672c\u6cd5\u9662\u62cd\u5356\u4e0d\u52a8\u4ea7\u4fe1\u606f\u7f51\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/workbao.net\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/workbao.net\/#organization\",\"name\":\"\u51fa\u6d77\u8d22\u7ecf\u54a8\u8be2\uff08\u6df1\u5733\uff09\u6709\u9650\u516c\u53f8\",\"url\":\"https:\/\/workbao.net\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/workbao.net\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/workbao.net\/wp-content\/uploads\/2021\/07\/img2.png\",\"contentUrl\":\"https:\/\/workbao.net\/wp-content\/uploads\/2021\/07\/img2.png\",\"width\":53,\"height\":55,\"caption\":\"\u51fa\u6d77\u8d22\u7ecf\u54a8\u8be2\uff08\u6df1\u5733\uff09\u6709\u9650\u516c\u53f8\"},\"image\":{\"@id\":\"https:\/\/workbao.net\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/profile.php?id=61567565904984\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/workbao.net\/#\/schema\/person\/0e790bad3408958a94de3d4e3da0619f\",\"name\":\"\u6a2a\u6ee8\u5730\u65b9\u6cd5\u9662\u5ddd\u5d0e\u652f\u90e8\",\"url\":\"https:\/\/workbao.net\/fr\/author\/c08e9d1dfca5373a\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u795e\u5948\u5ddd\u53bf\u5ddd\u5d0e\u5e02\u4e2d\u539f\u533a\u7684\u62cd\u5356\uff1a2434 \u4e07\u65e5\u5143 \u4e00\u6237\u5efa 110 \u5e73\u65b9\u7c73 - Japanese real estate auctioned by the court","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/workbao.net\/fr\/\u795e\u5948\u5ddd\u53bf\u5ddd\u5d0e\u5e02\u4e2d\u539f\u533a\u7684\u62cd\u5356\uff1a2434-\u4e07\u65e5\u5143-\u4e00\u6237\u5efa-110-\u5e73\/","og_locale":"fr_FR","og_type":"article","og_title":"\u795e\u5948\u5ddd\u53bf\u5ddd\u5d0e\u5e02\u4e2d\u539f\u533a\u7684\u62cd\u5356\uff1a2434 \u4e07\u65e5\u5143 \u4e00\u6237\u5efa 110 \u5e73\u65b9\u7c73","og_description":"\u6295\u6807\u65f6\u95f4\uff1a2024 \u5e74 8 \u6708 28 \u65e5\u81f3 9 \u6708 4 \u65e5\uff1b\u516c\u544a\u65e5\u671f\uff1a2024 \u5e74 8 \u6708 14 \u65e5\uff1b\u7ba1\u8f96\u6cd5\u9662\uff1a\u6a2a\u6ee8\u5730\u65b9\u6cd5\u9662\u5ddd\u5d0e\u652f\u90e8\uff1b\u6848\u4ef6\u7f16\u53f7\uff1a\u4ee4\u548c05\u5e74(\u30cc)\u7b2c50\u53f7\uff1b\u8f66\u7ad9\u8ddd\u79bb\uff1a\u65e5\u5409\u7ad9 11 \u5206\u949f\uff08\u7ea6 820 \u7c73\uff09\uff1b\u7ade\u4e70\u4fdd\u8bc1\u91d1\uff1a486.8 \u4e07\u65e5\u5143\u2026\u2026","og_url":"https:\/\/workbao.net\/fr\/\u795e\u5948\u5ddd\u53bf\u5ddd\u5d0e\u5e02\u4e2d\u539f\u533a\u7684\u62cd\u5356\uff1a2434-\u4e07\u65e5\u5143-\u4e00\u6237\u5efa-110-\u5e73\/","og_site_name":"Japanese real estate auctioned by the court","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=61567565904984","article_published_time":"2024-08-13T16:00:00+00:00","og_image":[{"width":400,"height":300,"url":"https:\/\/workbao.net\/wp-content\/uploads\/2024\/08\/e04ca3843f68c7e2c113b89c0f704778.jpg","type":"image\/jpeg"}],"author":"\u6a2a\u6ee8\u5730\u65b9\u6cd5\u9662\u5ddd\u5d0e\u652f\u90e8","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"\u6a2a\u6ee8\u5730\u65b9\u6cd5\u9662\u5ddd\u5d0e\u652f\u90e8"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/workbao.net\/zh\/%e7%a5%9e%e5%a5%88%e5%b7%9d%e5%8e%bf%e5%b7%9d%e5%b4%8e%e5%b8%82%e4%b8%ad%e5%8e%9f%e5%8c%ba%e7%9a%84%e6%8b%8d%e5%8d%96%ef%bc%9a2434-%e4%b8%87%e6%97%a5%e5%85%83-%e4%b8%80%e6%88%b7%e5%bb%ba-110-%e5%b9%b3\/#article","isPartOf":{"@id":"https:\/\/workbao.net\/zh\/%e7%a5%9e%e5%a5%88%e5%b7%9d%e5%8e%bf%e5%b7%9d%e5%b4%8e%e5%b8%82%e4%b8%ad%e5%8e%9f%e5%8c%ba%e7%9a%84%e6%8b%8d%e5%8d%96%ef%bc%9a2434-%e4%b8%87%e6%97%a5%e5%85%83-%e4%b8%80%e6%88%b7%e5%bb%ba-110-%e5%b9%b3\/"},"author":{"name":"\u6a2a\u6ee8\u5730\u65b9\u6cd5\u9662\u5ddd\u5d0e\u652f\u90e8","@id":"https:\/\/workbao.net\/#\/schema\/person\/0e790bad3408958a94de3d4e3da0619f"},"headline":"\u795e\u5948\u5ddd\u53bf\u5ddd\u5d0e\u5e02\u4e2d\u539f\u533a\u7684\u62cd\u5356\uff1a2434 \u4e07\u65e5\u5143 \u4e00\u6237\u5efa 110 \u5e73\u65b9\u7c73","datePublished":"2024-08-13T16:00:00+00:00","dateModified":"2024-08-13T16:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/workbao.net\/zh\/%e7%a5%9e%e5%a5%88%e5%b7%9d%e5%8e%bf%e5%b7%9d%e5%b4%8e%e5%b8%82%e4%b8%ad%e5%8e%9f%e5%8c%ba%e7%9a%84%e6%8b%8d%e5%8d%96%ef%bc%9a2434-%e4%b8%87%e6%97%a5%e5%85%83-%e4%b8%80%e6%88%b7%e5%bb%ba-110-%e5%b9%b3\/"},"wordCount":18,"publisher":{"@id":"https:\/\/workbao.net\/#organization"},"image":{"@id":"https:\/\/workbao.net\/zh\/%e7%a5%9e%e5%a5%88%e5%b7%9d%e5%8e%bf%e5%b7%9d%e5%b4%8e%e5%b8%82%e4%b8%ad%e5%8e%9f%e5%8c%ba%e7%9a%84%e6%8b%8d%e5%8d%96%ef%bc%9a2434-%e4%b8%87%e6%97%a5%e5%85%83-%e4%b8%80%e6%88%b7%e5%bb%ba-110-%e5%b9%b3\/#primaryimage"},"thumbnailUrl":"https:\/\/workbao.net\/wp-content\/uploads\/2024\/08\/e04ca3843f68c7e2c113b89c0f704778.jpg","keywords":["\u4e00\u6237\u5efa","\u5173\u4e1c\u5730\u65b9","\u5ddd\u5d0e\u5e02\u4e2d\u539f\u533a","\u6cd5\u9662","\u795e\u5948\u5ddd\u53bf"],"articleSection":["\u6a2a\u6ee8"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/workbao.net\/zh\/%e7%a5%9e%e5%a5%88%e5%b7%9d%e5%8e%bf%e5%b7%9d%e5%b4%8e%e5%b8%82%e4%b8%ad%e5%8e%9f%e5%8c%ba%e7%9a%84%e6%8b%8d%e5%8d%96%ef%bc%9a2434-%e4%b8%87%e6%97%a5%e5%85%83-%e4%b8%80%e6%88%b7%e5%bb%ba-110-%e5%b9%b3\/","url":"https:\/\/workbao.net\/zh\/%e7%a5%9e%e5%a5%88%e5%b7%9d%e5%8e%bf%e5%b7%9d%e5%b4%8e%e5%b8%82%e4%b8%ad%e5%8e%9f%e5%8c%ba%e7%9a%84%e6%8b%8d%e5%8d%96%ef%bc%9a2434-%e4%b8%87%e6%97%a5%e5%85%83-%e4%b8%80%e6%88%b7%e5%bb%ba-110-%e5%b9%b3\/","name":"\u795e\u5948\u5ddd\u53bf\u5ddd\u5d0e\u5e02\u4e2d\u539f\u533a\u7684\u62cd\u5356\uff1a2434 \u4e07\u65e5\u5143 \u4e00\u6237\u5efa 110 \u5e73\u65b9\u7c73 - Japanese real estate auctioned by the court","isPartOf":{"@id":"https:\/\/workbao.net\/#website"},"primaryImageOfPage":{"@id":"https:\/\/workbao.net\/zh\/%e7%a5%9e%e5%a5%88%e5%b7%9d%e5%8e%bf%e5%b7%9d%e5%b4%8e%e5%b8%82%e4%b8%ad%e5%8e%9f%e5%8c%ba%e7%9a%84%e6%8b%8d%e5%8d%96%ef%bc%9a2434-%e4%b8%87%e6%97%a5%e5%85%83-%e4%b8%80%e6%88%b7%e5%bb%ba-110-%e5%b9%b3\/#primaryimage"},"image":{"@id":"https:\/\/workbao.net\/zh\/%e7%a5%9e%e5%a5%88%e5%b7%9d%e5%8e%bf%e5%b7%9d%e5%b4%8e%e5%b8%82%e4%b8%ad%e5%8e%9f%e5%8c%ba%e7%9a%84%e6%8b%8d%e5%8d%96%ef%bc%9a2434-%e4%b8%87%e6%97%a5%e5%85%83-%e4%b8%80%e6%88%b7%e5%bb%ba-110-%e5%b9%b3\/#primaryimage"},"thumbnailUrl":"https:\/\/workbao.net\/wp-content\/uploads\/2024\/08\/e04ca3843f68c7e2c113b89c0f704778.jpg","datePublished":"2024-08-13T16:00:00+00:00","dateModified":"2024-08-13T16:00:00+00:00","breadcrumb":{"@id":"https:\/\/workbao.net\/zh\/%e7%a5%9e%e5%a5%88%e5%b7%9d%e5%8e%bf%e5%b7%9d%e5%b4%8e%e5%b8%82%e4%b8%ad%e5%8e%9f%e5%8c%ba%e7%9a%84%e6%8b%8d%e5%8d%96%ef%bc%9a2434-%e4%b8%87%e6%97%a5%e5%85%83-%e4%b8%80%e6%88%b7%e5%bb%ba-110-%e5%b9%b3\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/workbao.net\/zh\/%e7%a5%9e%e5%a5%88%e5%b7%9d%e5%8e%bf%e5%b7%9d%e5%b4%8e%e5%b8%82%e4%b8%ad%e5%8e%9f%e5%8c%ba%e7%9a%84%e6%8b%8d%e5%8d%96%ef%bc%9a2434-%e4%b8%87%e6%97%a5%e5%85%83-%e4%b8%80%e6%88%b7%e5%bb%ba-110-%e5%b9%b3\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/workbao.net\/zh\/%e7%a5%9e%e5%a5%88%e5%b7%9d%e5%8e%bf%e5%b7%9d%e5%b4%8e%e5%b8%82%e4%b8%ad%e5%8e%9f%e5%8c%ba%e7%9a%84%e6%8b%8d%e5%8d%96%ef%bc%9a2434-%e4%b8%87%e6%97%a5%e5%85%83-%e4%b8%80%e6%88%b7%e5%bb%ba-110-%e5%b9%b3\/#primaryimage","url":"https:\/\/workbao.net\/wp-content\/uploads\/2024\/08\/e04ca3843f68c7e2c113b89c0f704778.jpg","contentUrl":"https:\/\/workbao.net\/wp-content\/uploads\/2024\/08\/e04ca3843f68c7e2c113b89c0f704778.jpg","width":400,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/workbao.net\/zh\/%e7%a5%9e%e5%a5%88%e5%b7%9d%e5%8e%bf%e5%b7%9d%e5%b4%8e%e5%b8%82%e4%b8%ad%e5%8e%9f%e5%8c%ba%e7%9a%84%e6%8b%8d%e5%8d%96%ef%bc%9a2434-%e4%b8%87%e6%97%a5%e5%85%83-%e4%b8%80%e6%88%b7%e5%bb%ba-110-%e5%b9%b3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u9996\u9875","item":"https:\/\/workbao.net\/"},{"@type":"ListItem","position":2,"name":"\u795e\u5948\u5ddd\u53bf\u5ddd\u5d0e\u5e02\u4e2d\u539f\u533a\u7684\u62cd\u5356\uff1a2434 \u4e07\u65e5\u5143 \u4e00\u6237\u5efa 110 \u5e73\u65b9\u7c73"}]},{"@type":"WebSite","@id":"https:\/\/workbao.net\/#website","url":"https:\/\/workbao.net\/","name":"Japanese real estate auctioned by the court","description":"\u4e3a\u5168\u7403\u5916\u56fd\u4eba\u6295\u8d44\u65e5\u672c\u4e0d\u52a8\u4ea7\uff0c\u63d0\u4f9b\u6cd5\u9662\uff08\u542b\u653f\u5e9c\uff09\u62cd\u5356\u623f\u4ea7\u4fe1\u606f\u3002\uff08\u63d0\u793a\uff1a1.\u6cd5\u9662\u62cd\u5356\u4ea7\u6743\u6e05\u6670\uff0c\u4ef7\u683c\u4fbf\u5b9c\uff0c\u53ef\u80fd\u6361\u6f0f\u5b9d\u8d1d\uff1b2.\u6295\u6807\u65e5\u672c\u6cd5\u62cd\u623f\uff0c\u8bf7\u9075\u5b88\u65e5\u672c\u6cd5\u9662\u76f8\u5173\u653f\u7b56\u4e0e\u89c4\u5b9a\uff09","publisher":{"@id":"https:\/\/workbao.net\/#organization"},"alternateName":"\u65e5\u672c\u6cd5\u9662\u62cd\u5356\u4e0d\u52a8\u4ea7\u4fe1\u606f\u7f51","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/workbao.net\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/workbao.net\/#organization","name":"\u51fa\u6d77\u8d22\u7ecf\u54a8\u8be2\uff08\u6df1\u5733\uff09\u6709\u9650\u516c\u53f8","url":"https:\/\/workbao.net\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/workbao.net\/#\/schema\/logo\/image\/","url":"https:\/\/workbao.net\/wp-content\/uploads\/2021\/07\/img2.png","contentUrl":"https:\/\/workbao.net\/wp-content\/uploads\/2021\/07\/img2.png","width":53,"height":55,"caption":"\u51fa\u6d77\u8d22\u7ecf\u54a8\u8be2\uff08\u6df1\u5733\uff09\u6709\u9650\u516c\u53f8"},"image":{"@id":"https:\/\/workbao.net\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61567565904984"]},{"@type":"Person","@id":"https:\/\/workbao.net\/#\/schema\/person\/0e790bad3408958a94de3d4e3da0619f","name":"\u6a2a\u6ee8\u5730\u65b9\u6cd5\u9662\u5ddd\u5d0e\u652f\u90e8","url":"https:\/\/workbao.net\/fr\/author\/c08e9d1dfca5373a\/"}]}},"jetpack_featured_media_url":"https:\/\/workbao.net\/wp-content\/uploads\/2024\/08\/e04ca3843f68c7e2c113b89c0f704778.jpg","publishpress_future_action":{"enabled":false,"date":"2026-06-25 19:55:32","action":"category","newStatus":"draft","terms":[107],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"rttpg_featured_image_url":{"full":["https:\/\/workbao.net\/wp-content\/uploads\/2024\/08\/e04ca3843f68c7e2c113b89c0f704778.jpg",400,300,false],"landscape":["https:\/\/workbao.net\/wp-content\/uploads\/2024\/08\/e04ca3843f68c7e2c113b89c0f704778.jpg",400,300,false],"portraits":["https:\/\/workbao.net\/wp-content\/uploads\/2024\/08\/e04ca3843f68c7e2c113b89c0f704778.jpg",400,300,false],"thumbnail":["https:\/\/workbao.net\/wp-content\/uploads\/2024\/08\/e04ca3843f68c7e2c113b89c0f704778-150x150.jpg",150,150,true],"medium":["https:\/\/workbao.net\/wp-content\/uploads\/2024\/08\/e04ca3843f68c7e2c113b89c0f704778-300x225.jpg",300,225,true],"large":["https:\/\/workbao.net\/wp-content\/uploads\/2024\/08\/e04ca3843f68c7e2c113b89c0f704778.jpg",400,300,false],"1536x1536":["https:\/\/workbao.net\/wp-content\/uploads\/2024\/08\/e04ca3843f68c7e2c113b89c0f704778.jpg",400,300,false],"2048x2048":["https:\/\/workbao.net\/wp-content\/uploads\/2024\/08\/e04ca3843f68c7e2c113b89c0f704778.jpg",400,300,false],"trp-custom-language-flag":["https:\/\/workbao.net\/wp-content\/uploads\/2024\/08\/e04ca3843f68c7e2c113b89c0f704778.jpg",16,12,false],"mynote-thumbnail":["https:\/\/workbao.net\/wp-content\/uploads\/2024\/08\/e04ca3843f68c7e2c113b89c0f704778-360x240.jpg",360,240,true],"mynote-medium":["https:\/\/workbao.net\/wp-content\/uploads\/2024\/08\/e04ca3843f68c7e2c113b89c0f704778.jpg",400,300,false],"tenweb_optimizer_mobile":["https:\/\/workbao.net\/wp-content\/uploads\/2024\/08\/e04ca3843f68c7e2c113b89c0f704778.jpg",400,300,false],"tenweb_optimizer_tablet":["https:\/\/workbao.net\/wp-content\/uploads\/2024\/08\/e04ca3843f68c7e2c113b89c0f704778.jpg",400,300,false]},"rttpg_author":{"display_name":"\u6a2a\u6ee8\u5730\u65b9\u6cd5\u9662\u5ddd\u5d0e\u652f\u90e8","author_link":"https:\/\/workbao.net\/fr\/author\/c08e9d1dfca5373a\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/workbao.net\/fr\/sujets\/10ville\/hengbin\/\" rel=\"tag\">\u6a2a\u6ee8<\/a>","rttpg_excerpt":"\u6295\u6807\u65f6\u95f4\uff1a2024 \u5e74 8 \u6708 28 \u65e5\u81f3 9 \u6708 4 \u65e5\uff1b\u516c\u544a\u65e5\u671f\uff1a2024 \u5e74 8 \u6708 14 \u65e5\uff1b\u7ba1\u8f96\u6cd5\u9662\u2026","_links":{"self":[{"href":"https:\/\/workbao.net\/fr\/wp-json\/wp\/v2\/posts\/20178","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/workbao.net\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/workbao.net\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/workbao.net\/fr\/wp-json\/wp\/v2\/users\/120"}],"replies":[{"embeddable":true,"href":"https:\/\/workbao.net\/fr\/wp-json\/wp\/v2\/comments?post=20178"}],"version-history":[{"count":0,"href":"https:\/\/workbao.net\/fr\/wp-json\/wp\/v2\/posts\/20178\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/workbao.net\/fr\/wp-json\/wp\/v2\/media\/20179"}],"wp:attachment":[{"href":"https:\/\/workbao.net\/fr\/wp-json\/wp\/v2\/media?parent=20178"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/workbao.net\/fr\/wp-json\/wp\/v2\/categories?post=20178"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/workbao.net\/fr\/wp-json\/wp\/v2\/tags?post=20178"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}